{"id":572899,"date":"2025-03-28T12:47:17","date_gmt":"2025-03-28T11:47:17","guid":{"rendered":"https:\/\/donkersvagparts.nl\/product\/20446300-4g9012171-stuetze-sonstige\/"},"modified":"2026-02-22T01:42:26","modified_gmt":"2026-02-22T00:42:26","slug":"20446300-4g9012171-stuetze-sonstige","status":"publish","type":"product","link":"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/","title":{"rendered":"20446300 \u2013 4G9012171 \u2013 St\u00fctze (sonstige)"},"content":{"rendered":"<p>Steun voor bevestigingsoog<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Steun voor bevestigingsoog<\/p>\n","protected":false},"featured_media":408692,"template":"","meta":{"_acf_changed":false,"_eb_attr":""},"product_brand":[],"product_cat":[133,139],"product_tag":[],"class_list":{"0":"post-572899","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-motor-und-zubehoer","7":"product_cat-sonstige-teile","9":"first","10":"instock","11":"sold-individually","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>20446300 \u2013 4G9012171 \u2013 St\u00fctze (sonstige) - Donkers VAG Parts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20446300 \u2013 4G9012171 \u2013 St\u00fctze (sonstige) - Donkers VAG Parts\" \/>\n<meta property=\"og:description\" content=\"Steun voor bevestigingsoog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/\" \/>\n<meta property=\"og:site_name\" content=\"Donkers VAG Parts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-22T00:42:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2025\/03\/0874a024-44ed-41f4-8181-92c7bd8bcc0e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/20446300-4g9012171-stuetze-sonstige\\\/\",\"url\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/20446300-4g9012171-stuetze-sonstige\\\/\",\"name\":\"20446300 \u2013 4G9012171 \u2013 St\u00fctze (sonstige) - Donkers VAG Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/20446300-4g9012171-stuetze-sonstige\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/20446300-4g9012171-stuetze-sonstige\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/donkersvagparts.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0874a024-44ed-41f4-8181-92c7bd8bcc0e.jpg\",\"datePublished\":\"2025-03-28T11:47:17+00:00\",\"dateModified\":\"2026-02-22T00:42:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/20446300-4g9012171-stuetze-sonstige\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/20446300-4g9012171-stuetze-sonstige\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/20446300-4g9012171-stuetze-sonstige\\\/#primaryimage\",\"url\":\"https:\\\/\\\/donkersvagparts.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0874a024-44ed-41f4-8181-92c7bd8bcc0e.jpg\",\"contentUrl\":\"https:\\\/\\\/donkersvagparts.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0874a024-44ed-41f4-8181-92c7bd8bcc0e.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/20446300-4g9012171-stuetze-sonstige\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"20446300 \u2013 4G9012171 \u2013 St\u00fctze (sonstige)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/\",\"name\":\"Donkers VAG Parts\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#organization\",\"name\":\"Donkers VAG Parts\",\"url\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/donkersvagparts.nl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Donkers-VAG-parts-logo.png\",\"contentUrl\":\"https:\\\/\\\/donkersvagparts.nl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Donkers-VAG-parts-logo.png\",\"width\":1454,\"height\":178,\"caption\":\"Donkers VAG Parts\"},\"image\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20446300 \u2013 4G9012171 \u2013 St\u00fctze (sonstige) - Donkers VAG Parts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/","og_locale":"de_DE","og_type":"article","og_title":"20446300 \u2013 4G9012171 \u2013 St\u00fctze (sonstige) - Donkers VAG Parts","og_description":"Steun voor bevestigingsoog","og_url":"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/","og_site_name":"Donkers VAG Parts","article_modified_time":"2026-02-22T00:42:26+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2025\/03\/0874a024-44ed-41f4-8181-92c7bd8bcc0e.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/","url":"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/","name":"20446300 \u2013 4G9012171 \u2013 St\u00fctze (sonstige) - Donkers VAG Parts","isPartOf":{"@id":"https:\/\/donkersvagparts.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/#primaryimage"},"image":{"@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/#primaryimage"},"thumbnailUrl":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2025\/03\/0874a024-44ed-41f4-8181-92c7bd8bcc0e.jpg","datePublished":"2025-03-28T11:47:17+00:00","dateModified":"2026-02-22T00:42:26+00:00","breadcrumb":{"@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/#primaryimage","url":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2025\/03\/0874a024-44ed-41f4-8181-92c7bd8bcc0e.jpg","contentUrl":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2025\/03\/0874a024-44ed-41f4-8181-92c7bd8bcc0e.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/20446300-4g9012171-stuetze-sonstige\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/donkersvagparts.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/donkersvagparts.nl\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"20446300 \u2013 4G9012171 \u2013 St\u00fctze (sonstige)"}]},{"@type":"WebSite","@id":"https:\/\/donkersvagparts.nl\/de\/#website","url":"https:\/\/donkersvagparts.nl\/de\/","name":"Donkers VAG Parts","description":"","publisher":{"@id":"https:\/\/donkersvagparts.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/donkersvagparts.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/donkersvagparts.nl\/de\/#organization","name":"Donkers VAG Parts","url":"https:\/\/donkersvagparts.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/donkersvagparts.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2026\/01\/Donkers-VAG-parts-logo.png","contentUrl":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2026\/01\/Donkers-VAG-parts-logo.png","width":1454,"height":178,"caption":"Donkers VAG Parts"},"image":{"@id":"https:\/\/donkersvagparts.nl\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/product\/572899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/media\/408692"}],"wp:attachment":[{"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/media?parent=572899"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/product_brand?post=572899"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/product_cat?post=572899"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/product_tag?post=572899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}