{"id":556332,"date":"2025-03-28T21:41:16","date_gmt":"2025-03-28T20:41:16","guid":{"rendered":"https:\/\/donkersvagparts.nl\/product\/19302438-5q1423051bc-lenkgetriebe-servo\/"},"modified":"2026-02-22T01:40:36","modified_gmt":"2026-02-22T00:40:36","slug":"19302438-5q1423051bc-lenkgetriebe-servo","status":"publish","type":"product","link":"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/","title":{"rendered":"19302438 \u2013 5Q1423051BC \u2013 Lenkgetriebe Servo"},"content":{"rendered":"<p>Stuurhuis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stuurhuis<\/p>\n","protected":false},"featured_media":435232,"template":"","meta":{"_acf_changed":false,"_eb_attr":""},"product_brand":[],"product_cat":[521],"product_tag":[],"class_list":{"0":"post-556332","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-steuerung","8":"first","9":"instock","10":"sold-individually","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>19302438 \u2013 5Q1423051BC \u2013 Lenkgetriebe Servo - Donkers VAG Parts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"19302438 \u2013 5Q1423051BC \u2013 Lenkgetriebe Servo - Donkers VAG Parts\" \/>\n<meta property=\"og:description\" content=\"Stuurhuis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/\" \/>\n<meta property=\"og:site_name\" content=\"Donkers VAG Parts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-22T00:40:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2025\/03\/6e0d78bf-6a07-413e-8a53-c0e14d889f56.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/19302438-5q1423051bc-lenkgetriebe-servo\\\/\",\"url\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/19302438-5q1423051bc-lenkgetriebe-servo\\\/\",\"name\":\"19302438 \u2013 5Q1423051BC \u2013 Lenkgetriebe Servo - Donkers VAG Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/19302438-5q1423051bc-lenkgetriebe-servo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/19302438-5q1423051bc-lenkgetriebe-servo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/donkersvagparts.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/6e0d78bf-6a07-413e-8a53-c0e14d889f56.jpg\",\"datePublished\":\"2025-03-28T20:41:16+00:00\",\"dateModified\":\"2026-02-22T00:40:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/19302438-5q1423051bc-lenkgetriebe-servo\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/19302438-5q1423051bc-lenkgetriebe-servo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/19302438-5q1423051bc-lenkgetriebe-servo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/donkersvagparts.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/6e0d78bf-6a07-413e-8a53-c0e14d889f56.jpg\",\"contentUrl\":\"https:\\\/\\\/donkersvagparts.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/6e0d78bf-6a07-413e-8a53-c0e14d889f56.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/produkt\\\/19302438-5q1423051bc-lenkgetriebe-servo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"19302438 \u2013 5Q1423051BC \u2013 Lenkgetriebe Servo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/\",\"name\":\"Donkers VAG Parts\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#organization\",\"name\":\"Donkers VAG Parts\",\"url\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/donkersvagparts.nl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Donkers-VAG-parts-logo.png\",\"contentUrl\":\"https:\\\/\\\/donkersvagparts.nl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Donkers-VAG-parts-logo.png\",\"width\":1454,\"height\":178,\"caption\":\"Donkers VAG Parts\"},\"image\":{\"@id\":\"https:\\\/\\\/donkersvagparts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"19302438 \u2013 5Q1423051BC \u2013 Lenkgetriebe Servo - Donkers VAG Parts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/","og_locale":"de_DE","og_type":"article","og_title":"19302438 \u2013 5Q1423051BC \u2013 Lenkgetriebe Servo - Donkers VAG Parts","og_description":"Stuurhuis","og_url":"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/","og_site_name":"Donkers VAG Parts","article_modified_time":"2026-02-22T00:40:36+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2025\/03\/6e0d78bf-6a07-413e-8a53-c0e14d889f56.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/","url":"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/","name":"19302438 \u2013 5Q1423051BC \u2013 Lenkgetriebe Servo - Donkers VAG Parts","isPartOf":{"@id":"https:\/\/donkersvagparts.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/#primaryimage"},"image":{"@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/#primaryimage"},"thumbnailUrl":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2025\/03\/6e0d78bf-6a07-413e-8a53-c0e14d889f56.jpg","datePublished":"2025-03-28T20:41:16+00:00","dateModified":"2026-02-22T00:40:36+00:00","breadcrumb":{"@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/#primaryimage","url":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2025\/03\/6e0d78bf-6a07-413e-8a53-c0e14d889f56.jpg","contentUrl":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2025\/03\/6e0d78bf-6a07-413e-8a53-c0e14d889f56.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/donkersvagparts.nl\/de\/produkt\/19302438-5q1423051bc-lenkgetriebe-servo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/donkersvagparts.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/donkersvagparts.nl\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"19302438 \u2013 5Q1423051BC \u2013 Lenkgetriebe Servo"}]},{"@type":"WebSite","@id":"https:\/\/donkersvagparts.nl\/de\/#website","url":"https:\/\/donkersvagparts.nl\/de\/","name":"Donkers VAG Parts","description":"","publisher":{"@id":"https:\/\/donkersvagparts.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/donkersvagparts.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/donkersvagparts.nl\/de\/#organization","name":"Donkers VAG Parts","url":"https:\/\/donkersvagparts.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/donkersvagparts.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2026\/01\/Donkers-VAG-parts-logo.png","contentUrl":"https:\/\/donkersvagparts.nl\/wp-content\/uploads\/2026\/01\/Donkers-VAG-parts-logo.png","width":1454,"height":178,"caption":"Donkers VAG Parts"},"image":{"@id":"https:\/\/donkersvagparts.nl\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/product\/556332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/media\/435232"}],"wp:attachment":[{"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/media?parent=556332"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/product_brand?post=556332"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/product_cat?post=556332"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/donkersvagparts.nl\/de\/wp-json\/wp\/v2\/product_tag?post=556332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}